{"id":1962,"date":"2014-03-08T14:39:42","date_gmt":"2014-03-08T14:39:42","guid":{"rendered":"http:\/\/crispelomundo.com.br\/cris-programa-encontro-com-fatima-bernardes-globo\/"},"modified":"2014-03-08T14:39:42","modified_gmt":"2014-03-08T14:39:42","slug":"cris-programa-encontro-com-fatima-bernardes-globo","status":"publish","type":"post","link":"https:\/\/crispelomundo.com.br\/es\/cris-programme-encontro-com-fatima-bernardes-globo\/","title":{"rendered":"Cris en el programa Encontro con F\u00e1tima Bernardes - Globo."},"content":{"rendered":"<h2 style=\"text-align: center;\">\u00a1El d\u00eda de una estrella!<\/h2>\n<p>Fui invitada por el programa Encontro com F\u00e1tima Bernardes de Globo y \u00a1me encant\u00f3!<br \/>\nTen\u00eda que hablar de mis escapadas y, para variar, \u00a1tengo muchas! Para los que quieran verlo, s\u00f3lo tienen que pinchar en los dos enlaces de abajo con mi participaci\u00f3n completa, no fue gran cosa, pero lo disfrut\u00e9 mucho.<\/p>\n<p><a href=\"https:\/\/globoplay.globo.com\/v\/3180506\/\" target=\"_blank\" rel=\"noopener\">A Cris le encanta el Carnaval y ya ha pasado un d\u00eda en Salvador.\u00a0<\/a><\/p>\n<p><a href=\"https:\/\/globoplay.globo.com\/v\/3180510\/\" target=\"_blank\" rel=\"noopener\">F\u00e1tima da consejos para disfrutar del viaje<\/a><\/p>\n<p><a href=\"http:\/\/crispelomundo.com\/wp-content\/uploads\/2014\/03\/Cris-na-Globo-7.jpg\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-2392\" src=\"http:\/\/crispelomundo.com\/wp-content\/uploads\/2014\/03\/Cris-na-Globo-7.jpg\" alt=\"Cris en Globo (7)\" width=\"499\" height=\"491\" title=\"- Cris por el mundo\"><\/a><br \/>\nYa os he hablado de mi viaje a Salvador, cuando fui s\u00f3lo un d\u00eda a disfrutar del carnaval de all\u00ed y si me pregunt\u00e1is si merece la pena, os dir\u00e9 con convicci\u00f3n, \u00a1SI!<br \/>\nEs genial decidir un viaje con poca antelaci\u00f3n, con un escalofr\u00edo en la barriga, dejarlo todo e irte, con tu propia ropa y con la \u00fanica intenci\u00f3n de divertirte.<br \/>\nInform\u00e9 de la experiencia aqu\u00ed y si quieres verla completa, s\u00f3lo tienes que hacer clic en el enlace.<br \/>\n<a href=\"https:\/\/crispelomundo.com\/carnaval-em-salvador\/\" target=\"_blank\" rel=\"noopener\">Parte 1\u00a0<\/a><br \/>\n<a href=\"https:\/\/crispelomundo.com\/o-bendito-carnaval-de-salvador\/\" target=\"_blank\" rel=\"noopener\">Parte 2\u00a0<\/a><br \/>\nPor supuesto, no a todo el mundo le va a gustar la idea, hay que tener un m\u00ednimo de esp\u00edritu aventurero y estar dispuesto a disfrutar de todos modos.<\/p>\n<p><a href=\"http:\/\/crispelomundo.com\/wp-content\/uploads\/2014\/03\/Cris-na-Globo-4.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-2394\" src=\"http:\/\/crispelomundo.com\/wp-content\/uploads\/2014\/03\/Cris-na-Globo-4.jpg\" alt=\"Cris en Globo (4)\" width=\"419\" height=\"341\" title=\"- Cris por el mundo\"><\/a><\/p>\n<p>Cuando fui, en realidad no me importaba si iba a poder comprar una caba\u00f1a o no, la idea principal era estar en el carnaval de Salvador y conocer un poco m\u00e1s de las fiestas de all\u00ed, as\u00ed que fui con todas mis fuerzas, decidiendo casi con poca antelaci\u00f3n que iba a viajar.<br \/>\nOjal\u00e1 pudiera hacerlo todos los a\u00f1os, pero hay que tener cuidado y mucha experiencia para viajar as\u00ed. Si quieres alg\u00fan consejo, preg\u00fantame y te ayudar\u00e9 en lo que pueda.<\/p>\n<p>Pero la entrevista no acab\u00f3 ah\u00ed.<br \/>\nTambi\u00e9n mencion\u00f3 un viaje en el que las dificultades no estaban previstas; despu\u00e9s de todo, \u00a1nadie sue\u00f1a con romperse un pie o contraer una infecci\u00f3n intestinal en el mismo viaje!<br \/>\nAh, as\u00ed que esa era basura, \u00bfeh?<br \/>\nEn absoluto. Me divert\u00ed mucho e incluso cre\u00e9 un texto sobre c\u00f3mo sobrevivir a los imprevistos cuando se viaja, <a href=\"https:\/\/crispelomundo.com\/imprevistos_viagem\/\" target=\"_blank\" rel=\"noopener\">haga clic aqu\u00ed<\/a> para disfrutar de los consejos, el principal es: DISFRUTA DE TODO LO QUE PUEDAS.<br \/>\nLa vida est\u00e1 hecha de elecciones y siempre tienes una segunda opci\u00f3n para aprovechar al m\u00e1ximo todo lo que puedas, <a href=\"https:\/\/crispelomundo.com\/video-porto-de-galinhas-pe\/\" target=\"_blank\" rel=\"noopener\">Hice un v\u00eddeo sobre este viaje <\/a>\u00a0\u00a0en \u00e9l se puede ver que no me perd\u00ed ni un segundo, despu\u00e9s de todo Porto de Galinhas es hermoso de todos modos.<br \/>\n\u00a1Espero que lo hayas disfrutado y hayas visto que incluso con imprevistos es posible disfrutar de un gran viaje!<br \/>\nAl final, las dificultades se convierten en grandes historias que contar. Por supuesto, no todos los viajes tienen problemas, \u00bfverdad? Disfrutemos tambi\u00e9n de los consejos que tenemos aqu\u00ed...<br \/>\n\u00bfHa tenido alg\u00fan problema?<br \/>\n<a href=\"http:\/\/crispelomundo.com\/wp-content\/uploads\/2014\/03\/Cris-na-Globo-5.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-large wp-image-2396\" src=\"http:\/\/crispelomundo.com\/wp-content\/uploads\/2014\/03\/Cris-na-Globo-5-1024x768.jpg\" alt=\"Cris en Globo (5)\" width=\"640\" height=\"480\" title=\"- Cris por el mundo\"><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Um dia de estrela! Fui convidada pelo programa Encontro com F\u00e1tima Bernardes na globo e de cara adorei o convite! Era para falar sobre minhas roubadas e para variar tenho muitas!! Para quem quiser assistir \u00e9 s\u00f3 clicar nos dois links abaixo com a minha participa\u00e7\u00e3o completa, n\u00e3o foi muita coisa, mas gostei muit\u00e3o. Cris [&hellip;]<\/p>","protected":false},"author":1,"featured_media":1963,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,24],"tags":[123,544,545,433,48,546,547,548,549,550,551,426,552,553,554,555,55,556],"class_list":["post-1962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-rio-de-janeiro","tag-carnaval","tag-cris-na-globo","tag-cris-no-programa-encontro","tag-cris-pelo-mundo","tag-crispelomundo","tag-curtir-um-dia-em-salvador","tag-encontro-com-fatima","tag-encontro-com-fatima-bernardes","tag-fatima-bernardes","tag-globo","tag-pe-quebrado","tag-perrengue","tag-programa-encontro","tag-so-uma-noite-em-salvador","tag-um-dia","tag-um-dia-em-salvador","tag-viagem","tag-viagem-que-nao-deu-certo"],"_links":{"self":[{"href":"https:\/\/crispelomundo.com.br\/es\/wp-json\/wp\/v2\/posts\/1962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crispelomundo.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/crispelomundo.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/crispelomundo.com.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/crispelomundo.com.br\/es\/wp-json\/wp\/v2\/comments?post=1962"}],"version-history":[{"count":0,"href":"https:\/\/crispelomundo.com.br\/es\/wp-json\/wp\/v2\/posts\/1962\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/crispelomundo.com.br\/es\/wp-json\/wp\/v2\/media\/1963"}],"wp:attachment":[{"href":"https:\/\/crispelomundo.com.br\/es\/wp-json\/wp\/v2\/media?parent=1962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/crispelomundo.com.br\/es\/wp-json\/wp\/v2\/categories?post=1962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/crispelomundo.com.br\/es\/wp-json\/wp\/v2\/tags?post=1962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}